{"id":570,"count":1,"description":"","link":"https:\/\/novasarc.com\/blog\/tag\/technological-innovation","name":"Technological Innovation","slug":"technological-innovation","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Technological Innovation Archives - Novas Arc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novasarc.com\/blog\/tag\/technological-innovation\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technological Innovation Archives - Novas Arc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novasarc.com\/blog\/tag\/technological-innovation\" \/>\n<meta property=\"og:site_name\" content=\"Novas Arc\" \/>\n<meta property=\"og:image\" content=\"https:\/\/novasarc.com\/blog\/wp-content\/uploads\/2022\/03\/Final-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"441\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ConnectNovasarc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/tag\\\/technological-innovation\",\"url\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/tag\\\/technological-innovation\",\"name\":\"Technological Innovation Archives - Novas Arc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/tag\\\/technological-innovation#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/tag\\\/technological-innovation#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/novasarc.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technological Innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/\",\"name\":\"Novas Arc\",\"description\":\"IT Consulting Services\",\"publisher\":{\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/#organization\",\"name\":\"Novas Arc\",\"url\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.novasarc.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Final-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.novasarc.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Final-logo.png\",\"width\":441,\"height\":297,\"caption\":\"Novas Arc\"},\"image\":{\"@id\":\"https:\\\/\\\/novasarc.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ConnectNovasarc\",\"https:\\\/\\\/www.instagram.com\\\/connect_novasarc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technological Innovation Archives - Novas Arc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novasarc.com\/blog\/tag\/technological-innovation","og_locale":"en_US","og_type":"article","og_title":"Technological Innovation Archives - Novas Arc","og_url":"https:\/\/novasarc.com\/blog\/tag\/technological-innovation","og_site_name":"Novas Arc","og_image":[{"width":441,"height":297,"url":"https:\/\/novasarc.com\/blog\/wp-content\/uploads\/2022\/03\/Final-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ConnectNovasarc","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/novasarc.com\/blog\/tag\/technological-innovation","url":"https:\/\/novasarc.com\/blog\/tag\/technological-innovation","name":"Technological Innovation Archives - Novas Arc","isPartOf":{"@id":"https:\/\/novasarc.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/novasarc.com\/blog\/tag\/technological-innovation#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/novasarc.com\/blog\/tag\/technological-innovation#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/novasarc.com\/blog"},{"@type":"ListItem","position":2,"name":"Technological Innovation"}]},{"@type":"WebSite","@id":"https:\/\/novasarc.com\/blog\/#website","url":"https:\/\/novasarc.com\/blog\/","name":"Novas Arc","description":"IT Consulting Services","publisher":{"@id":"https:\/\/novasarc.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novasarc.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/novasarc.com\/blog\/#organization","name":"Novas Arc","url":"https:\/\/novasarc.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/novasarc.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.novasarc.com\/wp-content\/uploads\/2022\/03\/Final-logo.png","contentUrl":"https:\/\/www.novasarc.com\/wp-content\/uploads\/2022\/03\/Final-logo.png","width":441,"height":297,"caption":"Novas Arc"},"image":{"@id":"https:\/\/novasarc.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ConnectNovasarc","https:\/\/www.instagram.com\/connect_novasarc"]}]}},"_links":{"self":[{"href":"https:\/\/novasarc.com\/blog\/wp-json\/wp\/v2\/tags\/570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasarc.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/novasarc.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/novasarc.com\/blog\/wp-json\/wp\/v2\/posts?tags=570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}